{"id":21053,"date":"2018-02-15T11:51:30","date_gmt":"2018-02-15T11:51:30","guid":{"rendered":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/?p=21053"},"modified":"2018-02-15T15:04:21","modified_gmt":"2018-02-15T15:04:21","slug":"politicas-espectro","status":"publish","type":"post","link":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/","title":{"rendered":"Nuevo reporte de la GSMA advierte sobre el impacto de las pol\u00edticas de espectro en la calidad de los servicios m\u00f3viles para los usuarios de Am\u00e9rica Latina"},"content":{"rendered":"<p><em>Las pol\u00edticas p\u00fablicas tienen impacto en la prestaci\u00f3n de servicios de pr\u00f3xima generaci\u00f3n en toda la regi\u00f3n. En Am\u00e9rica Latina, los precios son 60 por ciento m\u00e1s altos que en Europa<\/em><\/p>\n<p><strong>15 de febrero de 2018, Buenos Aires:<\/strong> La GSMA (asociaci\u00f3n global del ecosistema m\u00f3vil) lanz\u00f3 hoy el nuevo informe, \u2018Eficacia en la fijaci\u00f3n de los precios del espectro en Am\u00e9rica Latina: pol\u00edticas que fomenten una mejor calidad y mayor asequibilidad de los servicios m\u00f3viles\u2019. El reporte destaca que las pol\u00edticas de espectro en Am\u00e9rica Latina afectan la calidad de los servicios m\u00f3viles para los usuarios de toda la regi\u00f3n.<\/p>\n<p>El nuevo estudio analiza las tendencias en la fijaci\u00f3n de precios del espectro en 15 pa\u00edses latinoamericanos y subraya c\u00f3mo las decisiones de los reguladores sobre la fijaci\u00f3n de precios del espectro pueden tener un impacto negativo en la calidad y el costo de los servicios de banda ancha m\u00f3vil. Si bien las subastas siguen siendo un medio efectivo para la adjudicaci\u00f3n del espectro, los reguladores deben adoptar pol\u00edticas de espectro focalizadas en maximizar los beneficios a largo plazo para la sociedad, en lugar de aumentar el costo del espectro para obtener ganancias a corto plazo. En Am\u00e9rica Latina, los precios excesivos del espectro, que son casi el doble de los europeos, ejercen una importante presi\u00f3n financiera sobre la industria que afecta el despliegue de redes de pr\u00f3xima generaci\u00f3n.<\/p>\n<p>\u201cLos pa\u00edses latinoamericanos que no ponen espectro a disposici\u00f3n para redes de 4G y 5G e inflan los precios de manera artificial impiden el desarrollo de sus econom\u00edas digitales, demoran el cierre de la brecha digital y perjudican a los usuarios\u201d, coment\u00f3 Sebasti\u00e1n Cabello, Director Regional de la GSMA para Am\u00e9rica Latina. \u201cLos operadores m\u00f3viles necesitan tener acceso equitativo a suficiente espectro radioel\u00e9ctrico para prestar servicios de banda ancha m\u00f3vil asequibles y de alta calidad. Los gobiernos y los reguladores deben adoptar pol\u00edticas que sustenten esta premisa para fomentar el crecimiento de sus econom\u00edas digitales locales\u201d, agreg\u00f3.<\/p>\n<h3>Pol\u00edticas de espectro adecuadas<\/h3>\n<p>Seg\u00fan el reporte, los altos precios de las bandas de espectro para brindar capacidad, resultantes de las subastas, no son consecuencia de las fuerzas del mercado sino que se deben, principalmente, a decisiones pol\u00edticas, donde los reguladores fijan un elevado precio de reserva. Este enfoque ha generado que se inflen los precios en la regi\u00f3n, que son casi un 60 por ciento m\u00e1s altos que en Europa.<\/p>\n<p>La cantidad de espectro asignado a los operadores m\u00f3viles a\u00fan se ubica muy por debajo de los mercados de Asia, Europa y Am\u00e9rica del Norte y, como resultado, las subastas de espectro en Am\u00e9rica Latina a menudo se realizan en un entorno de incertidumbre y escasez de espectro1. La disponibilidad futura de frecuencias obliga a los operadores m\u00f3viles a aceptar estos precios m\u00e1s altos para garantizar competitividad a largo plazo en sus respectivos mercados. Muchos pa\u00edses latinoamericanos tambi\u00e9n presentan una trayectoria mixta de poner espectro a disposici\u00f3n en forma oportuna y comprometerse con futuras asignaciones.<\/p>\n<p>\u201cLos pa\u00edses de Am\u00e9rica Latina deben establecer pol\u00edticas que fomenten el desarrollo de redes de pr\u00f3xima generaci\u00f3n y brinden a los usuarios acceso asequible a los servicios m\u00f3viles\u201d, continu\u00f3 Cabello. \u201cLa demanda de servicios de datos m\u00f3viles por parte de los consumidores sigue en aumento, pero a menos que los gobiernos y los reguladores gestionen el espectro eficientemente y permitan procesos m\u00e1s transparentes, asequibles y alcanzables para los operadores, los costos no bajar\u00e1n lo suficiente y los usuarios no ver\u00e1n los beneficios\u201d, complet\u00f3.<\/p>\n<h3>Un precio muy alto<\/h3>\n<p>El informe confirma el v\u00ednculo entre el gasto total en el espectro y el precio de los datos, sosteniendo que una reducci\u00f3n en los costos del espectro tendr\u00eda un impacto positivo en la adopci\u00f3n de servicios para consumidores y empresas. Asimismo, sugiere que los altos costos tambi\u00e9n podr\u00edan impedir la aplicaci\u00f3n de incentivos para la competencia de precios. Entre otros problemas, podemos mencionar precios de reserva altos, derechos anuales de licencia, plazos de licencias cortos, obligaciones de cobertura inadecuadas e incertidumbre acerca de las renovaciones y las nuevas adjudicaciones.<\/p>\n<h3>Mejores pr\u00e1cticas en pol\u00edticas de fijaci\u00f3n de precios del espectro<\/h3>\n<p>El reporte alienta a los gobiernos y reguladores latinoamericanos a evaluar el impacto que tienen sus pol\u00edticas sobre el precio y la disponibilidad del espectro, en particular debido a que las redes 4G y 5G requieren cada vez m\u00e1s cantidad de espectro. Las pol\u00edticas adecuadas mejorar\u00e1n el acceso a la banda ancha, al mismo tiempo que ofrecer\u00e1n beneficios a la sociedad, como cerrar la brecha digital y fomentar el crecimiento de la econom\u00eda digital. Espec\u00edficamente, el informe plantea las siguientes recomendaciones de pol\u00edticas fundamentales:<\/p>\n<ol>\n<li>Establecer precios de reserva modestos por debajo del valor de mercado esperado y garantizar que los derechos anuales no sean prohibitivos.<\/li>\n<li>Ofrecer espectro al mercado en forma oportuna, proporcionar a los operadores una hoja de ruta sobre la disponibilidad y la liberaci\u00f3n de espectro en el futuro para que conozcan los requerimientos con anticipaci\u00f3n.<\/li>\n<li>Evitar condiciones de licencia onerosas, garantizando que los plazos de las licencias sean lo suficientemente largos y que los oferentes tengan garant\u00edas de renovaci\u00f3n adecuadas para poder obtener un nivel suficiente de retorno sobre las inversiones realizadas en la infraestructura de red.<\/li>\n<li>Adoptar las mejores pr\u00e1cticas en cuanto al dise\u00f1o de las adjudicaciones que prioricen la eficiencia y no los ingresos.<\/li>\n<\/ol>\n<p>El informe completo, <em>Eficacia en la fijaci\u00f3n de los precios del espectro en Am\u00e9rica Latina: pol\u00edticas que fomenten una mejor calidad y mayor asequibilidad de los servicios m\u00f3viles<\/em>, se encuentra disponible en <a href=\"https:\/\/www.gsma.com\/connectivity-for-good\/spectrum\/wp-content\/uploads\/2018\/02\/Effective-Spectrum-Pricing-in-Latin-America-SPA-full.pdf\">www.gsma.com\/connectivity-for-good\/spectrum\/wp-content\/uploads\/2018\/02\/Effective-Spectrum-Pricing-in-Latin-America-SPA-full.pdf<\/a>.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/ioc0gG2l3ho\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las pol\u00edticas p\u00fablicas tienen impacto en la prestaci\u00f3n <\/p>\n","protected":false},"author":3,"featured_media":21098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[58,45],"tags":[],"algolia_discover_type":[],"class_list":["post-21053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homepage-es","category-newsspa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.3 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nuevo reporte de la GSMA advierte sobre el impacto de las pol\u00edticas de espectro en la calidad de los servicios m\u00f3viles para los usuarios de Am\u00e9rica Latina | GSMA Am\u00e9rica Latina y el Caribe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevo reporte de la GSMA advierte sobre el impacto de las pol\u00edticas de espectro en la calidad de los servicios m\u00f3viles para los usuarios de Am\u00e9rica Latina | GSMA Am\u00e9rica Latina y el Caribe\" \/>\n<meta property=\"og:description\" content=\"Las pol\u00edticas p\u00fablicas tienen impacto en la prestaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/\" \/>\n<meta property=\"og:site_name\" content=\"GSMA Am\u00e9rica Latina y el Caribe\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-15T11:51:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-15T15:04:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gsma.com\/about-us\/regions\/latin-america\/wp-content\/uploads\/2018\/02\/banner-reporte-espectro-esp-01-01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1354\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"tskinner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gsma\" \/>\n<meta name=\"twitter:site\" content=\"@gsma\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"tskinner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nuevo reporte de la GSMA advierte sobre el impacto de las pol\u00edticas de espectro en la calidad de los servicios m\u00f3viles para los usuarios de Am\u00e9rica Latina | GSMA Am\u00e9rica Latina y el Caribe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/","og_locale":"es_ES","og_type":"article","og_title":"Nuevo reporte de la GSMA advierte sobre el impacto de las pol\u00edticas de espectro en la calidad de los servicios m\u00f3viles para los usuarios de Am\u00e9rica Latina | GSMA Am\u00e9rica Latina y el Caribe","og_description":"Las pol\u00edticas p\u00fablicas tienen impacto en la prestaci\u00f3n","og_url":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/","og_site_name":"GSMA Am\u00e9rica Latina y el Caribe","article_published_time":"2018-02-15T11:51:30+00:00","article_modified_time":"2018-02-15T15:04:21+00:00","og_image":[{"width":1354,"height":667,"url":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america\/wp-content\/uploads\/2018\/02\/banner-reporte-espectro-esp-01-01.png","type":"image\/png"}],"author":"tskinner","twitter_card":"summary_large_image","twitter_creator":"@gsma","twitter_site":"@gsma","twitter_misc":{"Escrito por":"tskinner","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/#article","isPartOf":{"@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/"},"author":{"name":"tskinner","@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/#\/schema\/person\/c3fabbd94571037adefc525b0dec1fc3"},"headline":"Nuevo reporte de la GSMA advierte sobre el impacto de las pol\u00edticas de espectro en la calidad de los servicios m\u00f3viles para los usuarios de Am\u00e9rica Latina","datePublished":"2018-02-15T11:51:30+00:00","dateModified":"2018-02-15T15:04:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/"},"wordCount":1034,"publisher":{"@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/#organization"},"image":{"@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/wp-content\/uploads\/2018\/02\/banner-reporte-espectro-esp-01-01.png","articleSection":["Homepage-es","newsspa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/","url":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/","name":"Nuevo reporte de la GSMA advierte sobre el impacto de las pol\u00edticas de espectro en la calidad de los servicios m\u00f3viles para los usuarios de Am\u00e9rica Latina | GSMA Am\u00e9rica Latina y el Caribe","isPartOf":{"@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/#primaryimage"},"image":{"@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/wp-content\/uploads\/2018\/02\/banner-reporte-espectro-esp-01-01.png","datePublished":"2018-02-15T11:51:30+00:00","dateModified":"2018-02-15T15:04:21+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/politicas-espectro\/#primaryimage","url":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/wp-content\/uploads\/2018\/02\/banner-reporte-espectro-esp-01-01.png","contentUrl":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/wp-content\/uploads\/2018\/02\/banner-reporte-espectro-esp-01-01.png","width":1354,"height":667},{"@type":"WebSite","@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/#website","url":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/","name":"GSMA Latin America and the Caribbean","description":"GSMA Am\u00e9rica Latina y el Caribe","publisher":{"@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/#organization","name":"GSMA","url":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/wp-content\/uploads\/2024\/09\/GSMA-Logo-Red-RGB_square.jpg","contentUrl":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/wp-content\/uploads\/2024\/09\/GSMA-Logo-Red-RGB_square.jpg","width":600,"height":600,"caption":"GSMA"},"image":{"@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gsma"]},{"@type":"Person","@id":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/#\/schema\/person\/c3fabbd94571037adefc525b0dec1fc3","name":"tskinner","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/599006af04a788c71b0d376c8f0ecade657ce58a9ba538aa56461964313de011?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599006af04a788c71b0d376c8f0ecade657ce58a9ba538aa56461964313de011?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599006af04a788c71b0d376c8f0ecade657ce58a9ba538aa56461964313de011?s=96&d=mm&r=g","caption":"tskinner"}}]}},"jetpack_publicize_connections":[],"featured_image_url":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/wp-content\/uploads\/2018\/02\/banner-reporte-espectro-esp-01-01.png","jetpack_shortlink":"https:\/\/wp.me\/p3mooC-5tz","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/wp-content\/uploads\/2018\/02\/banner-reporte-espectro-esp-01-01.png","_links":{"self":[{"href":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/wp-json\/wp\/v2\/posts\/21053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/wp-json\/wp\/v2\/comments?post=21053"}],"version-history":[{"count":6,"href":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/wp-json\/wp\/v2\/posts\/21053\/revisions"}],"predecessor-version":[{"id":21106,"href":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/wp-json\/wp\/v2\/posts\/21053\/revisions\/21106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/wp-json\/wp\/v2\/media\/21098"}],"wp:attachment":[{"href":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/wp-json\/wp\/v2\/media?parent=21053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/wp-json\/wp\/v2\/categories?post=21053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/wp-json\/wp\/v2\/tags?post=21053"},{"taxonomy":"algolia_discover_type","embeddable":true,"href":"https:\/\/www.gsma.com\/about-us\/regions\/latin-america-and-the-caribbean\/es\/wp-json\/wp\/v2\/algolia_discover_type?post=21053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}